{"id":151,"date":"2019-01-21T06:28:21","date_gmt":"2019-01-21T06:28:21","guid":{"rendered":"https:\/\/msexportsindia.com\/rootblast\/?page_id=151"},"modified":"2019-05-07T05:17:23","modified_gmt":"2019-05-07T05:17:23","slug":"more-info","status":"publish","type":"page","link":"https:\/\/dezignaweb.com\/newrootblast\/more-info\/","title":{"rendered":"More Info"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-151","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/pages\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":1,"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/pages\/151\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/pages\/151\/revisions\/152"}],"wp:attachment":[{"href":"https:\/\/dezignaweb.com\/newrootblast\/wp-json\/wp\/v2\/media?parent=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}